{"id":20252,"date":"2024-09-07T10:04:09","date_gmt":"2024-09-07T08:04:09","guid":{"rendered":"https:\/\/www.efdb.ch\/?p=20252"},"modified":"2024-09-06T09:02:30","modified_gmt":"2024-09-06T07:02:30","slug":"menus-elementaire-du-9-au-13-septembre-2024","status":"publish","type":"post","link":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/","title":{"rendered":"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>MENU<\/strong><\/p><p style=\"text-align: center;\">Semaine du 9 au 13 septembre<\/p><p>&nbsp;<\/p><p style=\"text-align: center;\"><strong><span style=\"color: #ff0000;\">Menu classique<\/span><\/strong><\/p><p style=\"text-align: center;\"><strong>\u00a0<\/strong><\/p><p style=\"text-align: center;\"><strong>Lundi 9 septembre<\/strong><\/p><p style=\"text-align: center;\">Salade de cervelas et fromage<\/p><p style=\"text-align: center;\">Paupiettes de b\u0153uf<\/p><p style=\"text-align: center;\">Coquillettes<\/p><p style=\"text-align: center;\">Choux-raves<\/p><p style=\"text-align: center;\">Fruit Bio<\/p><p style=\"text-align: center;\"><strong>Mardi 10 septembre<\/strong><\/p><p style=\"text-align: center;\">Salade verte Bio<\/p><p style=\"text-align: center;\">Lard<\/p><p style=\"text-align: center;\">Pommes de terre au bouillon<\/p><p style=\"text-align: center;\">Haricots jaunes<\/p><p style=\"text-align: center;\">S\u00e9r\u00e9 aux fruits<\/p><p style=\"text-align: center;\"><strong>Mercredi 11 septembre<\/strong><\/p><p style=\"text-align: center;\">Salade de concombres et tomates<\/p><p style=\"text-align: center;\">Galette de bl\u00e9 et carottes<\/p><p style=\"text-align: center;\">P\u00e2tes<\/p><p style=\"text-align: center;\">Choux-fleurs Mimosa<\/p><p style=\"text-align: center;\">Biscuits<\/p><p style=\"text-align: center;\"><strong>Jeudi 12 septembre<\/strong><\/p><p style=\"text-align: center;\">Amuse-bouche au p\u00e2t\u00e9<\/p><p style=\"text-align: center;\">Rago\u00fbt de poulet au coco<\/p><p style=\"text-align: center;\">Riz aux l\u00e9gumes<\/p><p style=\"text-align: center;\">Courgettes<\/p><p style=\"text-align: center;\">Yaourt Cr\u00e9mo<\/p><p style=\"text-align: center;\"><strong>Vendredi 13 septembre<\/strong><\/p><p style=\"text-align: center;\">Mini croissant au jambon<\/p><p style=\"text-align: center;\">B\u00e2tonnets de poisson pan\u00e9 &#8211; sauce r\u00e9moulade<\/p><p style=\"text-align: center;\">Pommes de terre saut\u00e9es aux herbes<\/p><p style=\"text-align: center;\">Carottes<\/p><p style=\"text-align: center;\">Fruit<\/p><p>&nbsp;<\/p><hr \/><p>&nbsp;<\/p><p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><strong>Menu v\u00e9g\u00e9tarien<\/strong><\/span><\/p><p style=\"text-align: center;\"><strong>Lundi 9 septembre<\/strong><\/p><p style=\"text-align: center;\">Salade de carottes<\/p><p style=\"text-align: center;\">R\u00f4ti de flocons d\u2019avoine et l\u00e9gumes<\/p><p style=\"text-align: center;\">Coquillettes<\/p><p style=\"text-align: center;\">Choux-raves<\/p><p style=\"text-align: center;\">Fruit Bio<\/p><p style=\"text-align: center;\"><strong>Mardi 10 septembre<\/strong><\/p><p style=\"text-align: center;\">Salade verte Bio<\/p><p style=\"text-align: center;\">Boulettes v\u00e9g\u00e9tariennes en sauce<\/p><p style=\"text-align: center;\">Pommes de terre au bouillon<\/p><p style=\"text-align: center;\">Haricots jaunes<\/p><p style=\"text-align: center;\">S\u00e9r\u00e9 aux fruits<\/p><p style=\"text-align: center;\"><strong>Mercredi 11 septembre<\/strong><\/p><p style=\"text-align: center;\">Salade de concombres et tomates<\/p><p style=\"text-align: center;\">Galette de bl\u00e9 et carottes<\/p><p style=\"text-align: center;\">P\u00e2tes<\/p><p style=\"text-align: center;\">Choux-fleurs Mimosa<\/p><p style=\"text-align: center;\">Biscuits<\/p><p style=\"text-align: center;\"><strong>Jeudi 12 septembre<\/strong><\/p><p style=\"text-align: center;\">Amuse-bouche au fromage<\/p><p style=\"text-align: center;\">Ragout de Quorn au coco<\/p><p style=\"text-align: center;\">Riz aux l\u00e9gumes<\/p><p style=\"text-align: center;\">Courgettes<\/p><p style=\"text-align: center;\">Yaourt Cr\u00e9mo<\/p><p style=\"text-align: center;\"><strong>Vendredi 13 septembre<\/strong><\/p><p style=\"text-align: center;\">Tartelette aux l\u00e9gumes<\/p><p style=\"text-align: center;\">Nuggets v\u00e9gans &#8211; Sauce r\u00e9moulade<\/p><p style=\"text-align: center;\">Pommes de terre saut\u00e9es aux herbes<\/p><p style=\"text-align: center;\">Carottes<\/p><p style=\"text-align: center;\">Fruit<\/p>","protected":false},"excerpt":{"rendered":"<p>MENUSemaine du 9 au 13 septembre&nbsp;Menu classique\u00a0Lundi 9 septembreSalade de cervelas et fromagePaupiettes de b\u0153ufCoquillettesChoux-ravesFruit BioMardi 10 septembreSalade verte BioLardPommes de terre au bouillonHaricots jaunesS\u00e9r\u00e9 aux fruitsMercredi 11 septembreSalade de concombres et tomatesGalette de bl\u00e9 et carottesP\u00e2tesChoux-fleurs MimosaBiscuitsJeudi 12 septembreAmuse-bouche au p\u00e2t\u00e9Rago\u00fbt de poulet au cocoRiz aux l\u00e9gumesCourgettesYaourt Cr\u00e9moVendredi 13 septembreMini croissant au jambonB\u00e2tonnets de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-20252","post","type-post","status-publish","format-standard","hentry","category-cantine-elementaire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024 - EFDB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024 - EFDB\" \/>\n<meta property=\"og:description\" content=\"MENUSemaine du 9 au 13 septembre&nbsp;Menu classique\u00a0Lundi 9 septembreSalade de cervelas et fromagePaupiettes de b\u0153ufCoquillettesChoux-ravesFruit BioMardi 10 septembreSalade verte BioLardPommes de terre au bouillonHaricots jaunesS\u00e9r\u00e9 aux fruitsMercredi 11 septembreSalade de concombres et tomatesGalette de bl\u00e9 et carottesP\u00e2tesChoux-fleurs MimosaBiscuitsJeudi 12 septembreAmuse-bouche au p\u00e2t\u00e9Rago\u00fbt de poulet au cocoRiz aux l\u00e9gumesCourgettesYaourt Cr\u00e9moVendredi 13 septembreMini croissant au jambonB\u00e2tonnets de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"EFDB\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-07T08:04:09+00:00\" \/>\n<meta name=\"author\" content=\"elementaire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"elementaire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/menus-elementaire-du-9-au-13-septembre-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/menus-elementaire-du-9-au-13-septembre-2024\\\/\"},\"author\":{\"name\":\"elementaire\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#\\\/schema\\\/person\\\/dbd54f20fa2ff82ade0c1ec429cfc90f\"},\"headline\":\"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024\",\"datePublished\":\"2024-09-07T08:04:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/menus-elementaire-du-9-au-13-septembre-2024\\\/\"},\"wordCount\":210,\"commentCount\":0,\"articleSection\":[\"Cantine El\u00e9mentaire\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.efdb.ch\\\/de\\\/menus-elementaire-du-9-au-13-septembre-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/menus-elementaire-du-9-au-13-septembre-2024\\\/\",\"url\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/menus-elementaire-du-9-au-13-septembre-2024\\\/\",\"name\":\"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024 - EFDB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#website\"},\"datePublished\":\"2024-09-07T08:04:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#\\\/schema\\\/person\\\/dbd54f20fa2ff82ade0c1ec429cfc90f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/menus-elementaire-du-9-au-13-septembre-2024\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.efdb.ch\\\/de\\\/menus-elementaire-du-9-au-13-septembre-2024\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/menus-elementaire-du-9-au-13-septembre-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/\",\"name\":\"EFDB\",\"description\":\"\u00c9cole fran\u00e7aise de B\u00e2le\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#\\\/schema\\\/person\\\/dbd54f20fa2ff82ade0c1ec429cfc90f\",\"name\":\"elementaire\",\"url\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/author\\\/elementaire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024 - EFDB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/","og_locale":"de_DE","og_type":"article","og_title":"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024 - EFDB","og_description":"MENUSemaine du 9 au 13 septembre&nbsp;Menu classique\u00a0Lundi 9 septembreSalade de cervelas et fromagePaupiettes de b\u0153ufCoquillettesChoux-ravesFruit BioMardi 10 septembreSalade verte BioLardPommes de terre au bouillonHaricots jaunesS\u00e9r\u00e9 aux fruitsMercredi 11 septembreSalade de concombres et tomatesGalette de bl\u00e9 et carottesP\u00e2tesChoux-fleurs MimosaBiscuitsJeudi 12 septembreAmuse-bouche au p\u00e2t\u00e9Rago\u00fbt de poulet au cocoRiz aux l\u00e9gumesCourgettesYaourt Cr\u00e9moVendredi 13 septembreMini croissant au jambonB\u00e2tonnets de [&hellip;]","og_url":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/","og_site_name":"EFDB","article_published_time":"2024-09-07T08:04:09+00:00","author":"elementaire","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"elementaire","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/#article","isPartOf":{"@id":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/"},"author":{"name":"elementaire","@id":"https:\/\/www.efdb.ch\/de\/#\/schema\/person\/dbd54f20fa2ff82ade0c1ec429cfc90f"},"headline":"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024","datePublished":"2024-09-07T08:04:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/"},"wordCount":210,"commentCount":0,"articleSection":["Cantine El\u00e9mentaire"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/","url":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/","name":"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024 - EFDB","isPartOf":{"@id":"https:\/\/www.efdb.ch\/de\/#website"},"datePublished":"2024-09-07T08:04:09+00:00","author":{"@id":"https:\/\/www.efdb.ch\/de\/#\/schema\/person\/dbd54f20fa2ff82ade0c1ec429cfc90f"},"breadcrumb":{"@id":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.efdb.ch\/de\/menus-elementaire-du-9-au-13-septembre-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.efdb.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Menus \u00e9l\u00e9mentaire du 9 au 13 septembre 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.efdb.ch\/de\/#website","url":"https:\/\/www.efdb.ch\/de\/","name":"EFDB","description":"\u00c9cole fran\u00e7aise de B\u00e2le","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.efdb.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.efdb.ch\/de\/#\/schema\/person\/dbd54f20fa2ff82ade0c1ec429cfc90f","name":"elementaire","url":"https:\/\/www.efdb.ch\/de\/author\/elementaire\/"}]}},"_links":{"self":[{"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/posts\/20252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/comments?post=20252"}],"version-history":[{"count":4,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/posts\/20252\/revisions"}],"predecessor-version":[{"id":20270,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/posts\/20252\/revisions\/20270"}],"wp:attachment":[{"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/media?parent=20252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/categories?post=20252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/tags?post=20252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}