{"id":12929,"date":"2021-05-25T15:13:30","date_gmt":"2021-05-25T13:13:30","guid":{"rendered":"https:\/\/www.efdb.ch\/?p=12929"},"modified":"2021-06-14T12:23:03","modified_gmt":"2021-06-14T10:23:03","slug":"certifiee-cambridge-english-qualifications-2-2-2-4","status":"publish","type":"post","link":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/","title":{"rendered":"Vid\u00e9os de la classe de Moyenne Section &#8211; octobre 2020 \u00e0 mars 2021"},"content":{"rendered":"<p>D\u00e9couvrez en images un extrait des activit\u00e9s r\u00e9alis\u00e9es en classe de moyenne section de l&#8217;Ecole Fran\u00e7aise de B\u00e2le entre le mois d&#8217;octobre 2020 et le mois de mars 2021.<\/p><p>Par C\u00e9line Kern<\/p><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><iframe loading=\"lazy\" title=\"Octobre dans la classe des Moyens EFDB\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/7In5qUIQCxw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/figure><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><iframe loading=\"lazy\" title=\"Novembre dans la classe des Moyens EFDB\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/scpF4vGeySs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/figure><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><iframe loading=\"lazy\" title=\"D\u00e9cembre dans la classe des Moyens EFDB\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/HV_vbdOAMrM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/figure><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><iframe loading=\"lazy\" title=\"Janvier dans la classe des Moyens EFDB\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/Vk0UUg7BPSE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/figure><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><iframe loading=\"lazy\" title=\"F\u00e9vrier chez les Moyens EFDB\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/M_DnVHoutMI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/figure><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><iframe loading=\"lazy\" title=\"Mars chez les Moyens EFDB\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/XkyRL3SU3ro?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez en images un extrait des activit\u00e9s r\u00e9alis\u00e9es en classe de moyenne section de l&#8217;Ecole Fran\u00e7aise de B\u00e2le entre le mois d&#8217;octobre 2020 et le mois de mars 2021.Par C\u00e9line Kern<\/p>\n","protected":false},"author":4,"featured_media":12930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2,14],"tags":[],"class_list":["post-12929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-maternelle"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vid\u00e9os de la classe de Moyenne Section - octobre 2020 \u00e0 mars 2021 - EFDB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vid\u00e9os de la classe de Moyenne Section - octobre 2020 \u00e0 mars 2021 - EFDB\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez en images un extrait des activit\u00e9s r\u00e9alis\u00e9es en classe de moyenne section de l&#8217;Ecole Fran\u00e7aise de B\u00e2le entre le mois d&#8217;octobre 2020 et le mois de mars 2021.Par C\u00e9line Kern\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/\" \/>\n<meta property=\"og:site_name\" content=\"EFDB\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-25T13:13:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-14T10:23:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.efdb.ch\/wp-content\/uploads\/2021\/05\/Les-moyens-oct-a-mars.png\" \/>\n\t<meta property=\"og:image:width\" content=\"495\" \/>\n\t<meta property=\"og:image:height\" content=\"295\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"elementaire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"elementaire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/\"},\"author\":{\"name\":\"elementaire\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#\\\/schema\\\/person\\\/dbd54f20fa2ff82ade0c1ec429cfc90f\"},\"headline\":\"Vid\u00e9os de la classe de Moyenne Section &#8211; octobre 2020 \u00e0 mars 2021\",\"datePublished\":\"2021-05-25T13:13:30+00:00\",\"dateModified\":\"2021-06-14T10:23:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/\"},\"wordCount\":82,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.efdb.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Les-moyens-oct-a-mars.png\",\"articleSection\":[\"Blog\",\"Maternelle\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/\",\"url\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/\",\"name\":\"Vid\u00e9os de la classe de Moyenne Section - octobre 2020 \u00e0 mars 2021 - EFDB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.efdb.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Les-moyens-oct-a-mars.png\",\"datePublished\":\"2021-05-25T13:13:30+00:00\",\"dateModified\":\"2021-06-14T10:23:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#\\\/schema\\\/person\\\/dbd54f20fa2ff82ade0c1ec429cfc90f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.efdb.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Les-moyens-oct-a-mars.png\",\"contentUrl\":\"https:\\\/\\\/www.efdb.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Les-moyens-oct-a-mars.png\",\"width\":495,\"height\":295},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/certifiee-cambridge-english-qualifications-2-2-2-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vid\u00e9os de la classe de Moyenne Section &#8211; octobre 2020 \u00e0 mars 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/\",\"name\":\"EFDB\",\"description\":\"\u00c9cole fran\u00e7aise de B\u00e2le\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/#\\\/schema\\\/person\\\/dbd54f20fa2ff82ade0c1ec429cfc90f\",\"name\":\"elementaire\",\"url\":\"https:\\\/\\\/www.efdb.ch\\\/de\\\/author\\\/elementaire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vid\u00e9os de la classe de Moyenne Section - octobre 2020 \u00e0 mars 2021 - EFDB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/","og_locale":"de_DE","og_type":"article","og_title":"Vid\u00e9os de la classe de Moyenne Section - octobre 2020 \u00e0 mars 2021 - EFDB","og_description":"D\u00e9couvrez en images un extrait des activit\u00e9s r\u00e9alis\u00e9es en classe de moyenne section de l&#8217;Ecole Fran\u00e7aise de B\u00e2le entre le mois d&#8217;octobre 2020 et le mois de mars 2021.Par C\u00e9line Kern","og_url":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/","og_site_name":"EFDB","article_published_time":"2021-05-25T13:13:30+00:00","article_modified_time":"2021-06-14T10:23:03+00:00","og_image":[{"width":495,"height":295,"url":"https:\/\/www.efdb.ch\/wp-content\/uploads\/2021\/05\/Les-moyens-oct-a-mars.png","type":"image\/png"}],"author":"elementaire","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"elementaire","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/#article","isPartOf":{"@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/"},"author":{"name":"elementaire","@id":"https:\/\/www.efdb.ch\/de\/#\/schema\/person\/dbd54f20fa2ff82ade0c1ec429cfc90f"},"headline":"Vid\u00e9os de la classe de Moyenne Section &#8211; octobre 2020 \u00e0 mars 2021","datePublished":"2021-05-25T13:13:30+00:00","dateModified":"2021-06-14T10:23:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/"},"wordCount":82,"commentCount":0,"image":{"@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.efdb.ch\/wp-content\/uploads\/2021\/05\/Les-moyens-oct-a-mars.png","articleSection":["Blog","Maternelle"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/","url":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/","name":"Vid\u00e9os de la classe de Moyenne Section - octobre 2020 \u00e0 mars 2021 - EFDB","isPartOf":{"@id":"https:\/\/www.efdb.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/#primaryimage"},"image":{"@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.efdb.ch\/wp-content\/uploads\/2021\/05\/Les-moyens-oct-a-mars.png","datePublished":"2021-05-25T13:13:30+00:00","dateModified":"2021-06-14T10:23:03+00:00","author":{"@id":"https:\/\/www.efdb.ch\/de\/#\/schema\/person\/dbd54f20fa2ff82ade0c1ec429cfc90f"},"breadcrumb":{"@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/#primaryimage","url":"https:\/\/www.efdb.ch\/wp-content\/uploads\/2021\/05\/Les-moyens-oct-a-mars.png","contentUrl":"https:\/\/www.efdb.ch\/wp-content\/uploads\/2021\/05\/Les-moyens-oct-a-mars.png","width":495,"height":295},{"@type":"BreadcrumbList","@id":"https:\/\/www.efdb.ch\/de\/certifiee-cambridge-english-qualifications-2-2-2-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.efdb.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Vid\u00e9os de la classe de Moyenne Section &#8211; octobre 2020 \u00e0 mars 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.efdb.ch\/de\/#website","url":"https:\/\/www.efdb.ch\/de\/","name":"EFDB","description":"\u00c9cole fran\u00e7aise de B\u00e2le","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.efdb.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.efdb.ch\/de\/#\/schema\/person\/dbd54f20fa2ff82ade0c1ec429cfc90f","name":"elementaire","url":"https:\/\/www.efdb.ch\/de\/author\/elementaire\/"}]}},"_links":{"self":[{"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/posts\/12929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/comments?post=12929"}],"version-history":[{"count":3,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/posts\/12929\/revisions"}],"predecessor-version":[{"id":13068,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/posts\/12929\/revisions\/13068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/media\/12930"}],"wp:attachment":[{"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/media?parent=12929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/categories?post=12929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.efdb.ch\/de\/wp-json\/wp\/v2\/tags?post=12929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}